{"id":2,"count":19,"description":"","link":"https:\/\/filmzie.com\/blog\/category\/about-filmzie\/","name":"About Filmzie","slug":"about-filmzie","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>About Filmzie Archives - Filmzie Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/filmzie.com\/blog\/category\/about-filmzie\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"About Filmzie Archives - Filmzie Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/filmzie.com\/blog\/category\/about-filmzie\/\" \/>\n<meta property=\"og:site_name\" content=\"Filmzie Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/filmzie.com\\\/blog\\\/category\\\/about-filmzie\\\/\",\"url\":\"https:\\\/\\\/filmzie.com\\\/blog\\\/category\\\/about-filmzie\\\/\",\"name\":\"About Filmzie Archives - Filmzie Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/filmzie.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/filmzie.com\\\/blog\\\/category\\\/about-filmzie\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/filmzie.com\\\/blog\\\/category\\\/about-filmzie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/filmzie.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"About Filmzie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/filmzie.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/filmzie.com\\\/blog\\\/\",\"name\":\"Filmzie Blog\",\"description\":\"Watch free movies online!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/filmzie.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"About Filmzie Archives - Filmzie Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/filmzie.com\/blog\/category\/about-filmzie\/","og_locale":"en_US","og_type":"article","og_title":"About Filmzie Archives - Filmzie Blog","og_url":"https:\/\/filmzie.com\/blog\/category\/about-filmzie\/","og_site_name":"Filmzie Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/filmzie.com\/blog\/category\/about-filmzie\/","url":"https:\/\/filmzie.com\/blog\/category\/about-filmzie\/","name":"About Filmzie Archives - Filmzie Blog","isPartOf":{"@id":"https:\/\/filmzie.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/filmzie.com\/blog\/category\/about-filmzie\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/filmzie.com\/blog\/category\/about-filmzie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/filmzie.com\/blog\/"},{"@type":"ListItem","position":2,"name":"About Filmzie"}]},{"@type":"WebSite","@id":"https:\/\/filmzie.com\/blog\/#website","url":"https:\/\/filmzie.com\/blog\/","name":"Filmzie Blog","description":"Watch free movies online!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/filmzie.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/filmzie.com\/blog\/wp-json\/wp\/v2\/categories\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/filmzie.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/filmzie.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/filmzie.com\/blog\/wp-json\/wp\/v2\/posts?categories=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}